{"id":218,"date":"2026-06-01T16:04:54","date_gmt":"2026-06-01T14:04:54","guid":{"rendered":"https:\/\/docs.noblogs.org\/?p=218"},"modified":"2026-06-01T18:26:36","modified_gmt":"2026-06-01T16:26:36","slug":"gallery-lightbox","status":"publish","type":"post","link":"https:\/\/docs.noblogs.org\/en-US\/post\/2026\/06\/01\/gallery-lightbox\/","title":{"rendered":"Gallery lightbox"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">It is possible to use this feature only using gutenberg editor for post.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">To activate follow this guide: <a rel=\"noreferrer noopener\" href=\"https:\/\/docs.noblogs.org\/post\/2022\/06\/27\/attivare-il-block-editor\/\" target=\"_blank\">https:\/\/docs.noblogs.org\/post\/2022\/06\/27\/attivare-il-block-editor\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We activate on the network this plugin: <a rel=\"noreferrer noopener\" href=\"https:\/\/wordpress.org\/plugins\/gallery-block-lightbox\/\" target=\"_blank\">https:\/\/wordpress.org\/plugins\/gallery-block-lightbox\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">and we are happy because is light and minimal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">If you want use in your blog you need to activate:<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a572d6ba9841&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a572d6ba9841\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"391\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/Schermata-da-2023-04-04-17-21-07-1024x391.png\" alt=\"\" class=\"wp-image-195\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/Schermata-da-2023-04-04-17-21-07-1024x391.png 1024w, https:\/\/docs.noblogs.org\/files\/2023\/04\/Schermata-da-2023-04-04-17-21-07-300x115.png 300w, https:\/\/docs.noblogs.org\/files\/2023\/04\/Schermata-da-2023-04-04-17-21-07-768x294.png 768w, https:\/\/docs.noblogs.org\/files\/2023\/04\/Schermata-da-2023-04-04-17-21-07.png 1376w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">To have lightbox on your single image or gallery you have only to add it using the &#8220;block editor&#8221; and check the link to &#8220;media file&#8221;.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a572d6ba9b1c&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a572d6ba9b1c\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"495\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/docs.noblogs.org\/files\/2026\/06\/Screenshot-From-2026-06-01-16-07-41-1024x495.png\" alt=\"\" class=\"wp-image-723\" srcset=\"https:\/\/docs.noblogs.org\/files\/2026\/06\/Screenshot-From-2026-06-01-16-07-41-1024x495.png 1024w, https:\/\/docs.noblogs.org\/files\/2026\/06\/Screenshot-From-2026-06-01-16-07-41-300x145.png 300w, https:\/\/docs.noblogs.org\/files\/2026\/06\/Screenshot-From-2026-06-01-16-07-41-768x372.png 768w, https:\/\/docs.noblogs.org\/files\/2026\/06\/Screenshot-From-2026-06-01-16-07-41-1536x743.png 1536w, https:\/\/docs.noblogs.org\/files\/2026\/06\/Screenshot-From-2026-06-01-16-07-41.png 1918w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">In the Article or Page published you will see the lightbox in action.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">For other info follow the documentation of the plugin.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Sample gallery from Creative Commons Search: <a rel=\"noreferrer noopener\" href=\"https:\/\/openverse.org\/search\/?q=women%20working&amp;license_type=commercial,modification\" target=\"_blank\">women work<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww8.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"197\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww8.jpg\" alt=\"\" class=\"wp-image-197\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww8.jpg 1024w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww8-300x225.jpg 300w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww8-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww7.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"777\" data-id=\"198\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww7.jpg\" alt=\"\" class=\"wp-image-198\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww7.jpg 1023w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww7-300x228.jpg 300w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww7-768x583.jpg 768w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"715\" height=\"1000\" data-id=\"199\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww6.jpg\" alt=\"\" class=\"wp-image-199\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww6.jpg 715w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww6-215x300.jpg 215w\" sizes=\"auto, (max-width: 715px) 100vw, 715px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww5.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"596\" data-id=\"200\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww5.jpg\" alt=\"\" class=\"wp-image-200\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww5.jpg 1023w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww5-300x175.jpg 300w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww5-768x447.jpg 768w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"818\" data-id=\"201\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww4.jpg\" alt=\"\" class=\"wp-image-201\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww4.jpg 1024w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww4-300x240.jpg 300w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww4-768x614.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"796\" data-id=\"202\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww3.jpg\" alt=\"\" class=\"wp-image-202\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww3.jpg 1024w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww3-300x233.jpg 300w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww3-768x597.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"1024\" data-id=\"203\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww2.jpg\" alt=\"\" class=\"wp-image-203\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww2.jpg 796w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww2-233x300.jpg 233w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww2-768x988.jpg 768w\" sizes=\"auto, (max-width: 796px) 100vw, 796px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww9.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"382\" data-id=\"204\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww9.jpg\" alt=\"\" class=\"wp-image-204\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww9.jpg 500w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww9-300x229.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"661\" data-id=\"196\" src=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww1.jpg\" alt=\"\" class=\"wp-image-196\" srcset=\"https:\/\/docs.noblogs.org\/files\/2023\/04\/ww1.jpg 1024w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww1-300x194.jpg 300w, https:\/\/docs.noblogs.org\/files\/2023\/04\/ww1-768x496.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>It is possible to use this feature only using gutenberg editor for post. To activate follow this guide: https:\/\/docs.noblogs.org\/post\/2022\/06\/27\/attivare-il-block-editor\/ We activate on the network this plugin: https:\/\/wordpress.org\/plugins\/gallery-block-lightbox\/ and we are happy because is light and minimal. If you want use in your blog you need to activate: To have lightbox on your single image or [&hellip;]<\/p>\n","protected":false},"author":13862,"featured_media":723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_locale":"en_US","_original_post":"https:\/\/docs.noblogs.org\/?p=194","activitypub_content_warning":"","activitypub_content_visibility":"local","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-plugins","en-US"],"_links":{"self":[{"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/posts\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/users\/13862"}],"replies":[{"embeddable":true,"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/comments?post=218"}],"version-history":[{"count":8,"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/posts\/218\/revisions"}],"predecessor-version":[{"id":747,"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/posts\/218\/revisions\/747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/media\/723"}],"wp:attachment":[{"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/media?parent=218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/categories?post=218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/docs.noblogs.org\/wp-json\/wp\/v2\/tags?post=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}